{"id":3977,"date":"2023-04-12T17:02:17","date_gmt":"2023-04-12T15:02:17","guid":{"rendered":"https:\/\/cooperpharma.ma\/?page_id=3977"},"modified":"2024-04-16T13:13:09","modified_gmt":"2024-04-16T11:13:09","slug":"engagement-qualite","status":"publish","type":"page","link":"https:\/\/preprod.cooperpharma.ma\/en\/engagement-qualite\/","title":{"rendered":"Engagement Qualit\u00e9"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"3977\" class=\"elementor elementor-3977\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-c782d58 p-tb-50 pt-lg-110 pb-lg-80 cms-overlay-gradient-mode-bt elementor-section-boxed elementor-section-height-default elementor-section-height-default cms-remove-row-no cms-section-no-padding-no cms-boxed-bg-false cms-section-boxed-divider-false cms-overlay-gradient-bg-yes\" data-id=\"c782d58\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t<div class=\"cms-overlay-gradient\"><\/div><div class=\"cms-section-boxed-bg\"><\/div><div class=\"cms-section-boxed-divider\"><\/div><div class=\"cms-elementor-section-remove\"><\/div><div class=\"cms-elementor-section-corner cms-elementor-section-corner-top\"><\/div><div class=\"cms-elementor-section-corner cms-elementor-section-corner-bottom\"><\/div>\t\t\t<div class=\"elementor-container elementor-column-gap-default\" >\r\n\t\t\t        <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ae9c65e\" data-id=\"ae9c65e\" data-element_type=\"column\" data-e-type=\"column\">\r\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                \t\t<div class=\"elementor-element elementor-element-1636459 cms-heading-layout-2 elementor-widget__width-initial pb-30 elementor-widget-mobile__width-inherit elementor-widget-laptop__width-initial elementor-widget elementor-widget-cms_heading\" data-id=\"1636459\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"cms_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"cms-heading-wrapper text-center  text-lg-center\">\r\n        <h3 class=\"cms-mainheading heading mt-n5 text-lg-37 text-xl-40 lh-1-375  text-heading empty-none\">La qualit\u00e9 fait partie de la vision strat\u00e9gique du groupe Cooper Pharma. Nous \u0153uvrons quotidiennement pour offrir \u00e0 nos patients des produits aux normes internationales et de qualit\u00e9 irr\u00e9prochable.<br \/>\n<\/h3>\r\n    <div class=\"extra-space clearfix\"> <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98ec482 cms-heading-layout-2 elementor-widget__width-initial pb-30 elementor-widget-mobile__width-inherit elementor-widget-laptop__width-initial elementor-widget elementor-widget-cms_heading\" data-id=\"98ec482\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"cms_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"cms-heading-wrapper text-center  text-lg-center\">\r\n        <h3 class=\"cms-mainheading heading mt-n5 text-lg-37 text-xl-40 lh-1-375  text-heading empty-none\">Le souci de la qualit\u00e9 r\u00e9git toutes nos proc\u00e9dures internes et externes, en commen\u00e7ant par nos relations avec nos partenaires jusqu\u2019au produit final en passant par l\u2019achat des mati\u00e8res premi\u00e8res et des proc\u00e9d\u00e9s de fabrication et de contr\u00f4le.<\/h3>\r\n    <div class=\"extra-space clearfix\"> <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-2e049ef cms-overlay-gradient-primary pt-110 pb-40 elementor-section-boxed elementor-section-height-default elementor-section-height-default cms-remove-row-no cms-section-no-padding-no cms-boxed-bg-false cms-section-boxed-divider-false cms-overlay-gradient-bg-yes cms-overlay-gradient-mode-tb\" data-id=\"2e049ef\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t<div class=\"cms-overlay-gradient\"><\/div><div class=\"cms-section-boxed-bg\"><\/div><div class=\"cms-section-boxed-divider\"><\/div><div class=\"cms-elementor-section-remove\"><\/div><div class=\"cms-elementor-section-corner cms-elementor-section-corner-top\"><\/div><div class=\"cms-elementor-section-corner cms-elementor-section-corner-bottom\"><\/div>\t\t\t<div class=\"elementor-container elementor-column-gap-default\" >\r\n\t\t\t        <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b971aa8\" data-id=\"b971aa8\" data-element_type=\"column\" data-e-type=\"column\">\r\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                \t\t<div class=\"elementor-element elementor-element-eaa0374 cms-heading-layout-2 elementor-widget__width-initial pb-30 elementor-widget-mobile__width-inherit elementor-widget-laptop__width-initial elementor-widget elementor-widget-cms_heading\" data-id=\"eaa0374\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"cms_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"cms-heading-wrapper text-center  text-lg-center\">\r\n        <h3 class=\"cms-mainheading heading mt-n5 text-lg-37 text-xl-40 lh-1-375  text-white empty-none\">Notre d\u00e9marche nous a permis de d\u00e9crocher plusieurs certifications qualit\u00e9 nationales et internationales :<\/h3>\r\n    <div class=\"extra-space clearfix\"> <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8276807 elementor-widget elementor-widget-spacer\" data-id=\"8276807\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-034b201 cms-heading-layout-5 elementor-widget elementor-widget-cms_heading\" data-id=\"034b201\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"cms_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"cms-heading-wrapper text-\">\r\n    <div class=\"w-xl-50 w-lg-70\">\r\n    <\/div>\r\n    <div class=\"cms-heading-desc\">\r\n        <div class=\"cms-content-desc\">\r\n            <div class=\"cms-content-desc-inner row gutters-grid justify-content-between\"><div class=\"col-xl-6 col-lg-5\"><div class=\"relative d-inline-block\"><div class=\"cms-heading-experience shadow-primary\"><div class=\"cms-heading-experience-inner\">+90 ans d'exp\u00e9rience<\/div><\/div><img fetchpriority=\"high\" decoding=\"async\" class=\"cms-radius-20 rtl-flip cms-img\" src=\"https:\/\/preprod.cooperpharma.ma\/wp-content\/uploads\/2023\/05\/Screenshot-2023-05-14-at-18.57.17-1-620x498.png\" width=\"620\" height=\"498\" alt=\"Screenshot 2023-05-14 at 18.57.17\" title=\"Screenshot 2023-05-14 at 18.57.17\" \/><div class=\"cms-overlaps-divider cms-rounded-clippath-wrap-small\"><div class=\"cms-overlaps-divider1 cms-hexagon-clippath\"><\/div><div class=\"cms-overlaps-divider2 cms-hexagon2-clippath ml-4\"><\/div><\/div><\/div><\/div>                <div class=\"col-xl-5 col-lg-7\">                        <div class=\"cms-heading-features mt-45\">                                <div class=\"cms-heading-feature-item cms-list-item\"><div class=\"cms-list-item-inner row gutters-20 gutters-lg-40 align-items-center cms-animate-icon\"><div aria-hidden=\"true\" class=\"cms-icon col-auto cms-list-icon text-48 text-white cms-icon-animate cms-transition fas fa-certificate\" style=\"\"><\/div><div class=\"col\"><div class=\"cms-heading cms-list-title text-19 text-white\">Certification GMP<\/div><div class=\"cms-list-desc pt-20 text-white\">Par le minist\u00e8re de la Sant\u00e9 au Maroc,<\/div><\/div><\/div><\/div>\r\n                                                            <div class=\"cms-heading-feature-item cms-list-item mt-35\"><div class=\"cms-list-item-inner row gutters-20 gutters-lg-40 align-items-center cms-animate-icon\"><div aria-hidden=\"true\" class=\"cms-icon col-auto cms-list-icon text-48 text-white cms-icon-animate cms-transition chemlabsicon- chemlabs-icon-microscope\" style=\"\"><\/div><div class=\"col\"><div class=\"cms-heading cms-list-title text-19 text-white\">La certification AFSSAPS<\/div><div class=\"cms-list-desc pt-20 text-white\">(Aujourd\u2019hui ANSM) d\u00e9cern\u00e9e par l\u2019Agence Fran\u00e7aise pour la s\u00e9curit\u00e9 (aujourd\u2019hui ANSM) d\u00e9cern\u00e9e par l\u2019Agence Fran\u00e7aise pour la s\u00e9curit\u00e9 Sanitaire des Produits de Sant\u00e9 en 2008,<\/div><\/div><\/div><\/div>\r\n                                                            <div class=\"cms-heading-feature-item cms-list-item mt-35\"><div class=\"cms-list-item-inner row gutters-20 gutters-lg-40 align-items-center cms-animate-icon\"><div aria-hidden=\"true\" class=\"cms-icon col-auto cms-list-icon text-48 text-white cms-icon-animate cms-transition chemlabsicon- chemlabs-icon-test-tube1\" style=\"\"><\/div><div class=\"col\"><div class=\"cms-heading cms-list-title text-19 text-white\">La certification Saoudi FDA<\/div><div class=\"cms-list-desc pt-20 text-white\">En 2011 (Arabie Saoudite),<\/div><\/div><\/div><\/div>\r\n                                                            <div class=\"cms-heading-feature-item cms-list-item mt-35\"><div class=\"cms-list-item-inner row gutters-20 gutters-lg-40 align-items-center cms-animate-icon\"><div aria-hidden=\"true\" class=\"cms-icon col-auto cms-list-icon text-48 text-white cms-icon-animate cms-transition far fa-building\" style=\"\"><\/div><div class=\"col\"><div class=\"cms-heading cms-list-title text-19 text-white\">Manufacturing Site Registration Certificate<\/div><div class=\"cms-list-desc pt-20 text-white\">La certification \u00ab Manufacturing Site Registration Certificate \u00bb en 2015 (\u00c9mirats Arabes Unis).<\/div><\/div><\/div><\/div>\r\n                                                            <div class=\"cms-heading-feature-item cms-list-item mt-35\"><div class=\"cms-list-item-inner row gutters-20 gutters-lg-40 align-items-center cms-animate-icon\"><div aria-hidden=\"true\" class=\"cms-icon col-auto cms-list-icon text-48 text-white cms-icon-animate cms-transition fas fa-certificate\" style=\"\"><\/div><div class=\"col\"><div class=\"cms-heading cms-list-title text-19 text-white\">La certification Lybienne<\/div><div class=\"cms-list-desc pt-20 text-white\">En 2023<\/div><\/div><\/div><\/div>\r\n                                                    <\/div>\r\n                                    <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9746063 cms-tabs cms-tabs-layout-2 cms-tabs-view-horizontal elementor-widget elementor-widget-cms_tabs\" data-id=\"9746063\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"cms_tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"cms-tabs-wrap\">\r\n    <div class=\"cms-tabs-navigation elementor-hidden-tablet elementor-hidden-phone\">\r\n        <div class=\"cms-tabs-title cms-tabs-title-desktop row-cols-1 row-cols-md-2 row-cols-xl-4\">\r\n                            <div class=\"cms-tab-title cms-transition active\" data-target=\"#cms-tab-content-d240cfe\">\r\n                    <div class=\"cms-tab-title-inner cms-transitio\"><div aria-hidden=\"true\" class=\"cms-icon cms-tab-title-icon text-48 chemlabsicon- chemlabs-icon-flask2\" style=\"\"><\/div><div class=\"cms-tab-title-text text-17 font-700\"><span class=\"cms-tab-title-count\">1<\/span>Laboratoire de contr\u00f4le qualit\u00e9<\/div><\/div>\r\n                <\/div>\r\n                            <div class=\"cms-tab-title cms-transition\" data-target=\"#cms-tab-content-ba5980a\">\r\n                    <div class=\"cms-tab-title-inner cms-transitio\"><div aria-hidden=\"true\" class=\"cms-icon cms-tab-title-icon text-48 chemlabsicon- chemlabs-icon-Molecular\" style=\"\"><\/div><div class=\"cms-tab-title-text text-17 font-700\"><span class=\"cms-tab-title-count\">2<\/span>Mati\u00e8res premi\u00e8res <br> <\/div><\/div>\r\n                <\/div>\r\n                            <div class=\"cms-tab-title cms-transition\" data-target=\"#cms-tab-content-5a0d7f9\">\r\n                    <div class=\"cms-tab-title-inner cms-transitio\"><div aria-hidden=\"true\" class=\"cms-icon cms-tab-title-icon text-48 chemlabsicon- chemlabs-icon-bacteria\" style=\"\"><\/div><div class=\"cms-tab-title-text text-17 font-700\"><span class=\"cms-tab-title-count\">3<\/span>Contr\u00f4le<\/div><\/div>\r\n                <\/div>\r\n                    <\/div>\r\n    <\/div>\r\n    <div class=\"cms-tabs-content bg-white cms-shadow-1\">\r\n                    <div class=\"cms-tabs-title cms-tabs-title-mobile elementor-hidden-desktop\">\r\n                <div class=\"cms-tab-title cms-transition active\" data-target=\"#cms-tab-content-d240cfe\"><div class=\"cms-tab-title-inner cms-transitio\"><div aria-hidden=\"true\" class=\"cms-icon cms-tab-title-icon text-48 chemlabsicon- chemlabs-icon-flask2\" style=\"\"><\/div><div class=\"cms-tab-title-text text-17 font-700\"><span class=\"cms-tab-title-count\">1<\/span>Laboratoire de contr\u00f4le qualit\u00e9<\/div><\/div><\/div>\r\n            <\/div>\r\n            <div class=\"p-20 p-lg-40 p-xl-90 cms-tab-content cms-transition active\" id=\"cms-tab-content-d240cfe\" style=\"display:block;\">\r\n                                <div class=\"row gutters-xl-100 gutters-grid\">\r\n                    <div class=\"col-12 col-md-6 col-lg-auto\"><img decoding=\"async\" class=\"cms-img\" src=\"https:\/\/preprod.cooperpharma.ma\/wp-content\/uploads\/2024\/03\/Labo-controle-Qualite-pixabay-scaled-500x375.jpg\" width=\"500\" height=\"375\" alt=\"Labo controle Qualit\u00e9-pixabay\" title=\"Labo controle Qualit\u00e9-pixabay\" \/><\/div>                    <div class=\"col order-md-first\">\r\n                        <h3 class=\"cms-tab-content-heading cms-heading text-18 text-lg-24 mt-n5 pb-25\">Un laboratoire de contr\u00f4le qualit\u00e9. 80 collaborateurs exp\u00e9riment\u00e9s se chargent de diff\u00e9rents contr\u00f4les de conformit\u00e9 des produits.<\/h3>\r\n                        <div class=\"content-text text-16 pb-35\"><\/div>\r\n                                            <\/div>\r\n                <\/div>\r\n                            <\/div>\r\n                    <div class=\"cms-tabs-title cms-tabs-title-mobile elementor-hidden-desktop\">\r\n                <div class=\"cms-tab-title cms-transition\" data-target=\"#cms-tab-content-ba5980a\"><div class=\"cms-tab-title-inner cms-transitio\"><div aria-hidden=\"true\" class=\"cms-icon cms-tab-title-icon text-48 chemlabsicon- chemlabs-icon-Molecular\" style=\"\"><\/div><div class=\"cms-tab-title-text text-17 font-700\"><span class=\"cms-tab-title-count\">2<\/span>Mati\u00e8res premi\u00e8res <br> <\/div><\/div><\/div>\r\n            <\/div>\r\n            <div class=\"p-20 p-lg-40 p-xl-90 cms-tab-content cms-transition\" id=\"cms-tab-content-ba5980a\" style=\"display:none;\">\r\n                                <div class=\"row gutters-xl-100 gutters-grid\">\r\n                    <div class=\"col-12 col-md-6 col-lg-auto\"><img decoding=\"async\" class=\"cms-img\" src=\"https:\/\/preprod.cooperpharma.ma\/wp-content\/uploads\/2024\/03\/Matieres-premieres-pixabay-500x375.jpg\" width=\"500\" height=\"375\" alt=\"Mati\u00e8res premi\u00e8res-pixabay\" title=\"Mati\u00e8res premi\u00e8res-pixabay\" \/><\/div>                    <div class=\"col order-md-first\">\r\n                        <h3 class=\"cms-tab-content-heading cms-heading text-18 text-lg-24 mt-n5 pb-25\">Des mati\u00e8res premi\u00e8res r\u00e9pondant aux normes les plus strictes.<\/h3>\r\n                        <div class=\"content-text text-16 pb-35\"><\/div>\r\n                                            <\/div>\r\n                <\/div>\r\n                            <\/div>\r\n                    <div class=\"cms-tabs-title cms-tabs-title-mobile elementor-hidden-desktop\">\r\n                <div class=\"cms-tab-title cms-transition\" data-target=\"#cms-tab-content-5a0d7f9\"><div class=\"cms-tab-title-inner cms-transitio\"><div aria-hidden=\"true\" class=\"cms-icon cms-tab-title-icon text-48 chemlabsicon- chemlabs-icon-bacteria\" style=\"\"><\/div><div class=\"cms-tab-title-text text-17 font-700\"><span class=\"cms-tab-title-count\">3<\/span>Contr\u00f4le<\/div><\/div><\/div>\r\n            <\/div>\r\n            <div class=\"p-20 p-lg-40 p-xl-90 cms-tab-content cms-transition\" id=\"cms-tab-content-5a0d7f9\" style=\"display:none;\">\r\n                                <div class=\"row gutters-xl-100 gutters-grid\">\r\n                    <div class=\"col-12 col-md-6 col-lg-auto\"><img loading=\"lazy\" decoding=\"async\" class=\"cms-img\" src=\"https:\/\/preprod.cooperpharma.ma\/wp-content\/uploads\/2024\/03\/Controle-Environnement-500x375.jpg\" width=\"500\" height=\"375\" alt=\"Controle-Environnement\" title=\"Controle-Environnement\" \/><\/div>                    <div class=\"col order-md-first\">\r\n                        <h3 class=\"cms-tab-content-heading cms-heading text-18 text-lg-24 mt-n5 pb-25\">Un contr\u00f4le \u00e0 tous les niveaux de production pour prot\u00e9ger l\u2019environnement.<\/h3>\r\n                        <div class=\"content-text text-16 pb-35\"><\/div>\r\n                                            <\/div>\r\n                <\/div>\r\n                            <\/div>\r\n            <\/div>\r\n<\/div>  \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6438e5c elementor-widget elementor-widget-text-editor\" data-id=\"6438e5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><br><\/p><p>Ces certificats attestent de la conformit\u00e9 de nos produits aux normes internationales les plus strictes et la reconnaissance des partenaires les plus exigeants.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-4c320c6 elementor-section-boxed elementor-section-height-default elementor-section-height-default cms-remove-row-no cms-section-no-padding-no cms-boxed-bg-false cms-section-boxed-divider-false cms-overlay-gradient-bg-yes cms-overlay-gradient-mode-tb\" data-id=\"4c320c6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t<div class=\"cms-overlay-gradient\"><\/div><div class=\"cms-section-boxed-bg\"><\/div><div class=\"cms-section-boxed-divider\"><\/div><div class=\"cms-elementor-section-remove\"><\/div><div class=\"cms-elementor-section-corner cms-elementor-section-corner-top\"><\/div><div class=\"cms-elementor-section-corner cms-elementor-section-corner-bottom\"><\/div>\t\t\t<div class=\"elementor-container elementor-column-gap-default\" >\r\n\t\t\t        <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c294e28\" data-id=\"c294e28\" data-element_type=\"column\" data-e-type=\"column\">\r\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                \t\t<div class=\"elementor-element elementor-element-04850d8 elementor-widget elementor-widget-spacer\" data-id=\"04850d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54fb3ca cms-heading-layout-2 elementor-widget__width-initial pb-30 elementor-widget-mobile__width-inherit elementor-widget-laptop__width-initial elementor-widget elementor-widget-cms_heading\" data-id=\"54fb3ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"cms_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"cms-heading-wrapper text-center  text-lg-center\">\r\n        <div class=\"cms-smallheading mt-n5 mb-15 text-16 font-700  text-accent empty-none\">Cooper Pharma<\/div>\r\n    <div class=\"extra-space clearfix\"> <\/div>\r\n    <h3 class=\"cms-mainheading heading mt-n5 text-lg-37 text-xl-40 lh-1-375  text-secondary empty-none\">NOS LABELS & PRIX :<br \/>\n<\/h3>\r\n    <div class=\"extra-space clearfix\"> <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-d08a533 elementor-section-boxed elementor-section-height-default elementor-section-height-default cms-remove-row-no cms-section-no-padding-no cms-boxed-bg-false cms-section-boxed-divider-false cms-overlay-gradient-bg-yes cms-overlay-gradient-mode-tb\" data-id=\"d08a533\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\t<div class=\"cms-overlay-gradient\"><\/div><div class=\"cms-section-boxed-bg\"><\/div><div class=\"cms-section-boxed-divider\"><\/div><div class=\"cms-elementor-section-remove\"><\/div><div class=\"cms-elementor-section-corner cms-elementor-section-corner-top\"><\/div><div class=\"cms-elementor-section-corner cms-elementor-section-corner-bottom\"><\/div>\t\t\t<div class=\"elementor-container elementor-column-gap-default\" >\r\n\t\t\t        <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d35e2f6\" data-id=\"d35e2f6\" data-element_type=\"column\" data-e-type=\"column\">\r\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                \t\t<div class=\"elementor-element elementor-element-2cf2cbd cms-heading-layout-2 elementor-widget__width-initial pb-30 elementor-widget-mobile__width-inherit elementor-widget-laptop__width-initial elementor-widget elementor-widget-cms_heading\" data-id=\"2cf2cbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"cms_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"cms-heading-wrapper text-start  text-lg-start\">\r\n        <div class=\"cms-smallheading mt-n5 mb-15 text-16 font-700  text-accent empty-none\">LABEL RSE<\/div>\r\n    <div class=\"extra-space clearfix\"> <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6898009 elementor-widget elementor-widget-image\" data-id=\"6898009\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/preprod.cooperpharma.ma\/wp-content\/uploads\/elementor\/thumbs\/rse-rqfu5k9amijbdq5fbpdxbf46h7zfi771tjaso13hhg.jpg\" title=\"rse\" alt=\"rse\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4e0bac cms-heading-layout-3 elementor-widget elementor-widget-cms_heading\" data-id=\"a4e0bac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"cms_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"cms-heading-wrapper text-\">\r\n        <h2 class=\"cms-mainheading heading mt-n5 text-lg-37 lh-1-46  text-secondary empty-none\">En reconnaissance de notre engagement citoyen dans les domaines de la sant\u00e9, l\u2019\u00e9ducation et l\u2019environnement, nous nous sommes vus d\u00e9cerner, en 2014, le Label RSE de la CGEM (Conf\u00e9d\u00e9ration G\u00e9n\u00e9rale des Entreprises du Maroc).<\/h2>\r\n    <div class=\"extra-space clearfix\"> <\/div>\r\n    <div class=\"cms-heading-desc pt-40 pt-lg-70 empty-none\">    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7249e8 elementor-widget elementor-widget-spacer\" data-id=\"c7249e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-521abd8 elementor-section-boxed elementor-section-height-default elementor-section-height-default cms-remove-row-no cms-section-no-padding-no cms-boxed-bg-false cms-section-boxed-divider-false cms-overlay-gradient-bg-yes cms-overlay-gradient-mode-tb\" data-id=\"521abd8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t<div class=\"cms-overlay-gradient\"><\/div><div class=\"cms-section-boxed-bg\"><\/div><div class=\"cms-section-boxed-divider\"><\/div><div class=\"cms-elementor-section-remove\"><\/div><div class=\"cms-elementor-section-corner cms-elementor-section-corner-top\"><\/div><div class=\"cms-elementor-section-corner cms-elementor-section-corner-bottom\"><\/div>\t\t\t<div class=\"elementor-container elementor-column-gap-default\" >\r\n\t\t\t        <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6568aa5\" data-id=\"6568aa5\" data-element_type=\"column\" data-e-type=\"column\">\r\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                \t\t<div class=\"elementor-element elementor-element-fbb7833 elementor-widget elementor-widget-spacer\" data-id=\"fbb7833\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>La qualit\u00e9 fait partie de la vision strat\u00e9gique du groupe Cooper Pharma. Nous \u0153uvrons quotidiennement pour offrir \u00e0 nos patients des produits aux normes internationales et de qualit\u00e9 irr\u00e9prochable. Le souci de la qualit\u00e9 r\u00e9git toutes nos proc\u00e9dures internes et externes, en commen\u00e7ant par nos relations avec nos partenaires jusqu\u2019au produit final en passant par l\u2019achat des mati\u00e8res premi\u00e8res et des proc\u00e9d\u00e9s de fabrication et de contr\u00f4le. Notre d\u00e9marche nous a permis de d\u00e9crocher plusieurs certifications qualit\u00e9 nationales et internationales : +90 ans d&rsquo;exp\u00e9rience Certification GMPPar le minist\u00e8re de la Sant\u00e9 au Maroc, La certification AFSSAPS(Aujourd\u2019hui ANSM) d\u00e9cern\u00e9e par l\u2019Agence Fran\u00e7aise pour la s\u00e9curit\u00e9 (aujourd\u2019hui ANSM) d\u00e9cern\u00e9e par l\u2019Agence Fran\u00e7aise pour la s\u00e9curit\u00e9 Sanitaire des Produits de Sant\u00e9 en 2008, La certification Saoudi FDAEn 2011 (Arabie Saoudite), Manufacturing Site Registration CertificateLa certification \u00ab Manufacturing Site Registration Certificate \u00bb en 2015 (\u00c9mirats Arabes Unis). La certification LybienneEn 2023 1Laboratoire de contr\u00f4le qualit\u00e9 2Mati\u00e8res premi\u00e8res 3Contr\u00f4le 1Laboratoire de contr\u00f4le qualit\u00e9 Un laboratoire de contr\u00f4le qualit\u00e9. 80 collaborateurs exp\u00e9riment\u00e9s se chargent de diff\u00e9rents contr\u00f4les de conformit\u00e9 des produits. 2Mati\u00e8res premi\u00e8res Des mati\u00e8res premi\u00e8res r\u00e9pondant aux normes les plus strictes. 3Contr\u00f4le Un contr\u00f4le \u00e0 tous les niveaux de production pour prot\u00e9ger l\u2019environnement. Ces certificats attestent de la conformit\u00e9 de nos produits aux normes internationales les plus strictes et la reconnaissance des partenaires les plus exigeants. Cooper Pharma NOS LABELS &#038; PRIX : LABEL RSE En reconnaissance de notre engagement citoyen dans les domaines de la sant\u00e9, l\u2019\u00e9ducation et l\u2019environnement, nous nous sommes vus d\u00e9cerner, en 2014, le Label RSE de la CGEM (Conf\u00e9d\u00e9ration G\u00e9n\u00e9rale des Entreprises du Maroc).<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3977","page","type-page","status-publish","hentry","cms-no-post-thumbnail"],"lang":"fr","translations":{"fr":3977,"en":5797},"_links":{"self":[{"href":"https:\/\/preprod.cooperpharma.ma\/en\/wp-json\/wp\/v2\/pages\/3977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.cooperpharma.ma\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/preprod.cooperpharma.ma\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/preprod.cooperpharma.ma\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/preprod.cooperpharma.ma\/en\/wp-json\/wp\/v2\/comments?post=3977"}],"version-history":[{"count":175,"href":"https:\/\/preprod.cooperpharma.ma\/en\/wp-json\/wp\/v2\/pages\/3977\/revisions"}],"predecessor-version":[{"id":6005,"href":"https:\/\/preprod.cooperpharma.ma\/en\/wp-json\/wp\/v2\/pages\/3977\/revisions\/6005"}],"wp:attachment":[{"href":"https:\/\/preprod.cooperpharma.ma\/en\/wp-json\/wp\/v2\/media?parent=3977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}